{"id":3,"date":"2024-03-06T10:51:33","date_gmt":"2024-03-06T09:51:33","guid":{"rendered":"http:\/\/kerstinroes.de\/?page_id=3"},"modified":"2024-06-04T15:58:46","modified_gmt":"2024-06-04T13:58:46","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/kerstinroes.de\/index.php\/datenschutzerklaerung\/","title":{"rendered":"Impressum\/Datenschutzerkl\u00e4rung"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Impressum<\/h2>\n\n\n\n<p>Kerstin R\u00f6s<br>Kaiserstra\u00dfe 5a, 60311 Frankfurt am Main<br>Tel.: +49 (0)151-413 339 32<br>Mail: kr@roes-psych.de<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Haftungsausschluss<\/h5>\n\n\n\n<p><strong class=\"privacy-policy-tutorial\">Inhalt des Onlineangebots:<\/strong> Ich bem\u00fche mich, auf dieser Website richtige und vollst\u00e4ndige Informationen nach bestem Wissen und Gewissen zur Verf\u00fcgung zu stellen. Es wird jedoch keine Haftung oder Garantie f\u00fcr die Aktualit\u00e4t, Richtigkeit und Vollst\u00e4ndigkeit der bereitgestellten Informationen \u00fcbernommen.<\/p>\n\n\n\n<p><strong class=\"privacy-policy-tutorial\">Urheberrecht: <\/strong>Der Inhalt dieser Website ist urheberrechtlich gesch\u00fctzt. Aus Gr\u00fcnden des Urheberrechts ist die Speicherung und Vervielf\u00e4ltigung von Text\u0002und Bildmaterial oder Grafiken aus dieser Website nicht gestattet.<\/p>\n\n\n\n<p><strong class=\"privacy-policy-tutorial\">Datenschutzhinweis: <\/strong>Die Verwendung der Kontaktdaten des Impressums zur gewerblichen Werbung ist ausdr\u00fccklich nicht erw\u00fcnscht, es sei denn Kerstin R\u00f6s hatte zuvor ihre schriftliche Einwilligung erteilt oder es besteht bereits eine Gesch\u00e4ftsbeziehung. Kerstin R\u00f6s und alle auf dieser Website genannten Personen widersprechen hiermit jeder kommerziellen Verwendung und Weitergabe ihrer Daten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datenschutzerkl\u00e4rung<\/h2>\n\n\n\n<h5 class=\"wp-block-heading\">Erfassung allgemeiner Informationen<\/h5>\n\n\n\n<p>Wenn Sie auf meine Webseite zugreifen, werden automatisch Informationen allgemeiner Natur erfasst. Diese Informationen (Server-Logfiles) beinhalten etwa IP-Adresse, die Art des  Webbrowsers, das verwendete Betriebssystem, den Domainnamen Ihres Internet Service Providers und \u00c4hnliches. Hierbei handelt es sich ausschlie\u00dflich um Informationen, welche f\u00fcr uns keine R\u00fcckschl\u00fcsse auf Ihre Person zulassen. Diese Informationen sind technisch notwendig, um von Ihnen angeforderte Inhalte von Webseiten korrekt auszuliefern und fallen bei Nutzung des Internets zwingend an. Anonyme Informationen dieser Art werden von uns statistisch ausgewertet, um meinen Internetauftritt und die dahinterstehende Technik zu<br>optimieren.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Cookies<\/h5>\n\n\n\n<p>Wie viele andere Webseiten verwenden wir auch so genannte \u201eCookies\u201c. Cookies sind kleine Textdateien, die von einem Webseitenserver auf Ihre Festplatte \u00fcbertragen werden.<\/p>\n\n\n\n<p>Cookies k\u00f6nnen nicht verwendet werden, um Programme zu starten oder Viren auf einen Computer zu \u00fcbertragen. Anhand der in Cookies enthaltenen Informationen k\u00f6nnen wir Ihnen die Navigation erleichtern und die korrekte Anzeige unserer<br>Webseiten erm\u00f6glichen.<\/p>\n\n\n\n<p>In keinem Fall werden die erfassten Daten an Dritte weitergegeben oder ohne Ihre Einwilligung eine Verkn\u00fcpfung mit personenbezogenen Daten hergestellt.Nat\u00fcrlich k\u00f6nnen Sie unsere Website grunds\u00e4tzlich auch ohne Cookies betrachten. Internet-Browser sind regelm\u00e4\u00dfig so eingestellt, dass sie Cookies<br>akzeptieren. Sie k\u00f6nnen die Verwendung von Cookies jederzeit \u00fcber die Einstellungen Ihres Browsers deaktivieren. Bitte verwenden Sie die Hilfefunktionen Ihres Internetbrowsers, um zu erfahren, wie Sie diese Einstellungen \u00e4ndern k\u00f6nnen. Bitte<br>beachten Sie, dass einzelne Funktionen unserer Website m\u00f6glicherweise nicht funktionieren, wenn Sie die Verwendung von Cookies deaktiviert haben.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">SSL-Verschl\u00fcsselung<\/h5>\n\n\n\n<p>Um die Sicherheit Ihrer Daten bei der \u00dcbertragung zu sch\u00fctzen, verwenden wir dem aktuellen Stand der Technik entsprechende Verschl\u00fcsselungsverfahren (z. B. SSL) \u00fcber HTTPS.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Ihre Rechte auf Auskunft und L\u00f6schung<\/h5>\n\n\n\n<p>Sie haben das Recht, jederzeit Auskunft \u00fcber Ihre bei uns gespeicherten personenbezogenen Daten zu erhalten. Sie k\u00f6nnen auch die L\u00f6schung der Daten verlangen, dem wir aber nur entsprechen k\u00f6nnen, soweit keine Archivierungsverpflichtung f\u00fcr Gesundheitsdaten besteht. Die Kontaktdaten finden Sie unten.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Verwendung von Google Analytics<\/h5>\n\n\n\n<p>Diese Webseite benutzt Google Analytics, einen Webanalysedienst der Google Inc. (folgend: Google). Google Analytics verwendet sog. \u201eCookies\u201c, also Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Webseite durch Sie erm\u00f6glichen. Die durch das Cookie erzeugten Informationen<br>\u00fcber Ihre Benutzung dieser Webseite werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert.<\/p>\n\n\n\n<p>Aufgrund der Aktivierung der IP-Anonymisierung auf diesen Webseiten, wird Ihre IP-Adresse von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen  Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Webseite wird Google diese Informationen benutzen, um Ihre<br>Nutzung der Webseite auszuwerten, um Reports \u00fcber die Webseitenaktivit\u00e4ten zusammenzustellen und um weitere mit der Webseitennutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dem Webseitenbetreiber zu erbringen. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<\/p>\n\n\n\n<p>Sie k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; ich weise Sie jedoch darauf hin, dass Sie in diesem Fall<br>gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Webseite vollumf\u00e4nglich werden nutzen k\u00f6nnen. Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Webseite bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren: Browser-Add-on zur Deaktivierung von Google Analytics.<\/p>\n\n\n\n<p>Zus\u00e4tzlich oder als Alternative zum Browser-Add-On k\u00f6nnen Sie das Tracking durch Google Analytics auf unseren Seiten unterbinden, indem Sie diesen Link anklicken. Dabei wird ein Opt\u0002Out-Cookie auf Ihrem Ger\u00e4t installiert. Damit wird die Erfassung durch Google Analytics f\u00fcr diese Website und f\u00fcr diesen Browser zuk\u00fcnftig verhindert, so lange der Cookie in Ihrem Browser installiert bleibt.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Verwendung von Scriptbibliotheken (Google Webfronts)<\/h5>\n\n\n\n<p>Um meine Inhalte browser\u00fcbergreifend korrekt und grafisch ansprechend darzustellen, verwenden wir auf dieser Website Scriptbibliotheken und Schriftbibliotheken wie z. B. Google Webfonts (https:\/\/www.google.com\/webfonts\/). Google Webfonts werden zur Vermeidung mehrfachen Ladens in den Cache Ihres Browsers \u00fcbertragen. Falls der Browser die Google Webfonts nicht unterst\u00fctzt oder den Zugriff unterbindet, werden Inhalte in einer Standardschrift angezeigt.<\/p>\n\n\n\n<p>Der Aufruf von Scriptbibliotheken oder Schriftbibliotheken l\u00f6st automatisch eine Verbindung zum Betreiber der Bibliothek aus. Dabei ist es theoretisch m\u00f6glich \u2013 aktuell allerdings auch unklar ob und ggf. zu welchen Zwecken \u2013 dass Betreiber entsprechender Bibliotheken Daten erheben.<\/p>\n\n\n\n<p>Die Datenschutzrichtlinie des Bibliothekbetreibers Google finden Sie hier: <br>https:\/\/www.google.com\/policies\/privacy\/<\/p>\n\n\n\n<p>Eine Erkl\u00e4rung zum Umgang mit Google Webfonts finden Sie hier:<br>https:\/\/developers.google.com\/fonts\/faq<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Verwendung von Google Maps<\/h5>\n\n\n\n<p>Diese Webseite verwendet Google Maps, um geographische Informationen visuell darzustellen. Bei der Nutzung von Google Maps werden von Google auch Daten \u00fcber die Nutzung der Kartenfunktionen durch Besucher erhoben, verarbeitet und genutzt. N\u00e4here Informationen \u00fcber die Datenverarbeitung durch Google k\u00f6nnen Sie den Google-Datenschutzhinweisen entnehmen. Dort k\u00f6nnen Sie im Datenschutzcenter auch Ihre pers\u00f6nlichen Datenschutz-Einstellungen ver\u00e4ndern.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">\u00c4nderung meiner Datenschutzbestimmungen<\/h5>\n\n\n\n<p>Ich behalte mir vor, diese Datenschutzerkl\u00e4rung gelegentlich anzupassen, damit sie stets den aktuellen rechtlichen Anforderungen entspricht oder um \u00c4nderungen meiner<br>Leistungen in der Datenschutzerkl\u00e4rung umzusetzen, z. B. bei der Einf\u00fchrung neuer Services. F\u00fcr Ihren erneuten Besuch gilt dann die neue Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Fragen zum Datenschutz<\/h5>\n\n\n\n<p>Wenn Sie Fragen zum Datenschutz haben, schreiben Sie bitte eine E-Mail an <br>kr@roes-psych.de<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Recht auf Beschwerde bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<\/h5>\n\n\n\n<p>Als Betroffener steht Ihnen im Falle eines datenschutzrechtlichen Versto\u00dfes ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu. Zust\u00e4ndige Aufsichtsbeh\u00f6rde bez\u00fcglich datenschutzrechtlicher Fragen ist.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Der hessische Datenschutzbeauftragte<\/h5>\n\n\n\n<p>Anschrift: Gustav-Stresemann-Ring 1, 65189 Wiesbaden, Telefon: 0611 14080<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impressum Kerstin R\u00f6sKaiserstra\u00dfe 5a, 60311 Frankfurt am MainTel.: +49 (0)151-413 339 32Mail: kr@roes-psych.de Haftungsausschluss Inhalt des Onlineangebots: Ich bem\u00fche mich, auf dieser Website richtige und vollst\u00e4ndige Informationen nach bestem Wissen und Gewissen zur Verf\u00fcgung zu stellen. Es wird jedoch keine Haftung oder Garantie f\u00fcr die Aktualit\u00e4t, Richtigkeit und Vollst\u00e4ndigkeit der bereitgestellten Informationen \u00fcbernommen. Urheberrecht: Der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/pages\/3"}],"collection":[{"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":51,"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":573,"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/573"}],"wp:attachment":[{"href":"https:\/\/kerstinroes.de\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}